{"id":1272,"date":"2025-03-03T09:19:06","date_gmt":"2025-03-03T09:19:06","guid":{"rendered":"https:\/\/bsbagfactory.com\/?post_type=product&#038;p=1272"},"modified":"2025-08-23T04:02:54","modified_gmt":"2025-08-23T04:02:54","slug":"designer-duffle-bags","status":"publish","type":"product","link":"https:\/\/bsbagfactory.com\/fr_ca\/products\/designer-duffle-bags\/","title":{"rendered":"Sacs de sport de marque"},"content":{"rendered":"<p>Sacs de sport de marque<\/p>\n<table border=\"1\" cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td>LOGO<\/td>\n<td>Accepter le service OEM &amp; ODM \/ Personnalis\u00e9<\/td>\n<\/tr>\n<tr>\n<td>Type d'usine<\/td>\n<td>Production\/fabrication\/OEM\/transport \u00e0 guichet unique pour les clients<\/td>\n<\/tr>\n<tr>\n<td>MOQ<\/td>\n<td>50pcs en cuir v\u00e9ritable \/ 100pcs avec 2 couleurs dans d'autres mat\u00e9riaux.<\/td>\n<\/tr>\n<tr>\n<td>Code du mod\u00e8le<\/td>\n<td>BS00023<\/td>\n<\/tr>\n<tr>\n<td>Couleur<\/td>\n<td>Noir, rouge, bleu, marron ou couleurs personnalis\u00e9es accept\u00e9es.<\/td>\n<\/tr>\n<tr>\n<td>Type de mat\u00e9riaux<\/td>\n<td>Cuir v\u00e9ritable, cuir de Pu, cuir artificiel ou mat\u00e9riaux personnalis\u00e9s sont accept\u00e9s.<\/td>\n<\/tr>\n<tr>\n<td>Fonctionnalit\u00e9<\/td>\n<td>Grande capacit\u00e9 avec compartiments et options personnalisables.<\/td>\n<\/tr>\n<tr>\n<td>Capacit\u00e9 de production de l'usine<\/td>\n<td>500-1000pcs \/ jour, 30000pcs \/ mois<\/td>\n<\/tr>\n<tr>\n<td>D\u00e9lai de livraison de l'\u00e9chantillon<\/td>\n<td>5-7 jours. Selon la conception.<\/td>\n<\/tr>\n<tr>\n<td>D\u00e9lai de livraison des commandes en vrac<\/td>\n<td>30-45 jours. Selon la conception.<\/td>\n<\/tr>\n<tr>\n<td>Informations sur les dimensions<\/td>\n<td>Longueur*Largeur*Hauteur (25*9*20) cm. Les dimensions personnalis\u00e9es sont accept\u00e9es.<\/td>\n<\/tr>\n<tr>\n<td>M\u00e9thode d'emballage en usine<\/td>\n<td>1 pi\u00e8ce\/sac \u00e0 poussi\u00e8re\/sac en plastique ou un emballage personnalis\u00e9 est accept\u00e9.<\/td>\n<\/tr>\n<tr>\n<td>Mode d'exp\u00e9dition<\/td>\n<td>DHL, UPS, FEDEX, TNT, Aramex, EMS, China Post, par voie a\u00e9rienne, par voie maritime, etc.<\/td>\n<\/tr>\n<tr>\n<td>Service sp\u00e9cial<\/td>\n<td>Lettres m\u00e9talliques personnalis\u00e9es accept\u00e9es \/ Trouver des mat\u00e9riaux de sac sur le march\u00e9 \/ Une vari\u00e9t\u00e9 d'options de cr\u00e9ation de logos<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Avec l'acc\u00e9l\u00e9ration du rythme de la vie moderne et la diversification des besoins en mati\u00e8re de voyages et de loisirs, diff\u00e9rents types de sacs de voyage apparaissent les uns apr\u00e8s les autres. En tant que sac de voyage alliant mode, praticit\u00e9 et personnalisation, \"<a href=\"https:\/\/bsbagfactory.com\/fr_ca\/\">Sacs de sport de marque<\/a>Les \"Designer Duffle Bags\" sont de plus en plus pris\u00e9s par les cols blancs urbains, les hommes d'affaires et les amateurs de voyages. Les \"Designer Duffle Bags\", comme leur nom l'indique, sont des sacs \u00e0 dos ou des bagages \u00e0 main con\u00e7us avec soin par des designers, qui accordent une attention particuli\u00e8re aux d\u00e9tails et \u00e0 la qualit\u00e9. Ils r\u00e9pondent non seulement \u00e0 des normes \u00e9lev\u00e9es en mati\u00e8re de mat\u00e9riaux et d'artisanat, mais s'efforcent \u00e9galement de rompre avec les traditions en mati\u00e8re d'apparence et d'agencement fonctionnel, offrant ainsi aux consommateurs des sacs de boutique qui peuvent non seulement r\u00e9pondre aux besoins de voyage quotidiens, mais aussi faire preuve de go\u00fbt et de personnalit\u00e9. Cet article explique en d\u00e9tail ce qu'est un sac de voyage de marque, ses principales caract\u00e9ristiques, ses fonctions, ses sc\u00e9narios d'application et ses m\u00e9thodes d'entretien quotidien, afin d'aider chacun \u00e0 mieux comprendre ce sac de voyage \u00e0 la fois \u00e0 la mode et pratique.<\/p>\n<p>D\u00e9finition et principales caract\u00e9ristiques des sacs de sport de marque<br \/>\n1. D\u00e9finition des sacs de sport de marque<br \/>\n<a href=\"https:\/\/www.linkedin.com\/in\/markmyh\/\" rel=\"nofollow noopener\">Sacs de sport de marque<\/a> d\u00e9signe les sacs de voyage con\u00e7us par des \u00e9quipes de designers professionnels ou des designers r\u00e9put\u00e9s, fabriqu\u00e9s \u00e0 partir de mat\u00e9riaux de haute qualit\u00e9 et d'un savoir-faire exquis. Ce type de sac pr\u00e9sente g\u00e9n\u00e9ralement les caract\u00e9ristiques suivantes : grande capacit\u00e9, l\u00e9g\u00e8ret\u00e9, durabilit\u00e9 et aspect tendance. Il convient aux voyages de courte dur\u00e9e, aux voyages d'affaires, \u00e0 la remise en forme quotidienne, aux vacances de week-end et \u00e0 d'autres occasions. Par rapport aux sacs de sport ordinaires, les sacs de sport de marque accordent plus d'attention \u00e0 la conception, au traitement des d\u00e9tails et \u00e0 la transmission de la culture de la marque. Il s'agit d'un sac de style de vie \u00e0 la fois pratique et artistique.<\/p>\n<p>Principales caract\u00e9ristiques<br \/>\n(1) L'aspect de la mode<br \/>\nLes cr\u00e9ateurs utilisent g\u00e9n\u00e9ralement des concepts de design et des perspectives esth\u00e9tiques uniques pour faire de chaque sac de sport de marque un sac plein de personnalit\u00e9 et de modernit\u00e9. Qu'il s'agisse d'un style simple, d'un style r\u00e9tro ou d'un style sportif, ce type de sac peut montrer son charme unique gr\u00e2ce \u00e0 l'assortiment des couleurs, \u00e0 la conception des lignes et \u00e0 la s\u00e9lection des mat\u00e9riaux, devenant ainsi le point fort de la forme g\u00e9n\u00e9rale.<\/p>\n<p>(2) Mat\u00e9riaux haut de gamme et artisanat exquis<br \/>\nAfin de garantir la durabilit\u00e9 et la sensation du sac, les sacs de sport de marque utilisent souvent des mat\u00e9riaux de haute qualit\u00e9 tels que le cuir v\u00e9ritable, le nylon, le polyester haute densit\u00e9, et utilisent des coutures renforc\u00e9es, des fermetures \u00e9clair invisibles, une doublure anti-collision et d'autres proc\u00e9d\u00e9s pour rendre le sac non seulement agr\u00e9able \u00e0 l'\u0153il, mais aussi capable de r\u00e9sister \u00e0 l'\u00e9preuve du temps et de l'environnement pendant l'utilisation.<\/p>\n<p>(3) Grande capacit\u00e9 et conception multifonctionnelle<br \/>\nLes concepteurs mettent g\u00e9n\u00e9ralement l'accent sur l'aspect pratique de l'agencement fonctionnel, en concevant plusieurs compartiments, des poches en filet et des poches cach\u00e9es pour diviser raisonnablement l'espace dans le sac, ce qui est pratique pour ranger divers articles tels que des v\u00eatements, des produits \u00e9lectroniques, des documents et de l'\u00e9quipement de conditionnement physique. Qu'il s'agisse d'un voyage au long cours ou d'un d\u00e9placement quotidien, il peut r\u00e9pondre \u00e0 divers besoins.<\/p>\n<p>(4) Confort et portabilit\u00e9<br \/>\nCompte tenu de l'exp\u00e9rience de l'utilisateur qui porte un sac pendant une longue p\u00e9riode, de nombreux sacs de sport de marque accordent une attention particuli\u00e8re \u00e0 l'ergonomie dans la conception des sangles, des poign\u00e9es et des bandouli\u00e8res, en utilisant des mat\u00e9riaux de remplissage souples et des mod\u00e8les r\u00e9glables pour assurer le confort lors du transport d'objets lourds ou de la marche sur de longues distances, r\u00e9duisant ainsi le fardeau sur le corps.<\/p>\n<p>(5) D\u00e9tails et culture de la marque<br \/>\nLes cr\u00e9ateurs ajoutent souvent des logos de marque, des broderies uniques ou des motifs imprim\u00e9s aux sacs, faisant de chaque produit non seulement un outil, mais aussi une \u0153uvre d'art et un symbole d'identit\u00e9. Ces d\u00e9tails ne font pas que rehausser la beaut\u00e9 du sac, ils permettent \u00e9galement aux consommateurs de s'exprimer et d'exprimer leurs go\u00fbts.<\/p>\n<p>Analyse des fonctions principales<br \/>\n1. Fonction de stockage des voyages<br \/>\nLes sacs de voyage de marque sont largement utilis\u00e9s en voyage. Sa grande capacit\u00e9 permet de ranger facilement des v\u00eatements, des chaussures, des articles de toilette et des produits \u00e9lectroniques, r\u00e9pondant ainsi aux besoins de rangement des voyageurs de longue distance ou des voyageurs d'affaires de courte dur\u00e9e. La conception raisonnable des compartiments internes permet non seulement de s\u00e9parer efficacement les diff\u00e9rents articles afin d'\u00e9viter toute confusion, mais aussi de prot\u00e9ger les articles fragiles, garantissant ainsi la s\u00e9curit\u00e9 et l'ordre des articles pendant le voyage.<\/p>\n<p>2. Fonction voyages d'affaires<br \/>\nPour les hommes d'affaires qui voyagent fr\u00e9quemment, les sacs de voyage de marque peuvent \u00eatre utilis\u00e9s comme bagages et transporter des fournitures de bureau telles que des ordinateurs, des dossiers et des cartes de visite. Certains mod\u00e8les sont \u00e9galement con\u00e7us avec des compartiments sp\u00e9ciaux pour ordinateurs ou des couches anti-collision pour prot\u00e9ger les appareils \u00e9lectroniques des chocs ext\u00e9rieurs. En m\u00eame temps, l'aspect \u00e9l\u00e9gant et atmosph\u00e9rique peut \u00e9galement am\u00e9liorer l'image globale de l'entreprise et montrer le professionnalisme et le go\u00fbt.<\/p>\n<p>3. Forme physique et fonction d'exercice quotidien<br \/>\nAvec la popularit\u00e9 de la tendance au fitness, de plus en plus de personnes choisissent d'aller \u00e0 la salle de sport pour faire de l'exercice, et les sacs de sport de marque sont \u00e9galement devenus un choix id\u00e9al pour les sacs de fitness. L'espace int\u00e9rieur spacieux du sac peut accueillir des articles de sport essentiels tels que des v\u00eatements et des chaussures de sport, des serviettes et des bouteilles d'eau. En m\u00eame temps, la conception multi-poches \u00e0 l'int\u00e9rieur et \u00e0 l'ext\u00e9rieur facilite la prise et la mise en place des articles, r\u00e9duisant ainsi le travail de pr\u00e9paration fastidieux avant et apr\u00e8s l'entra\u00eenement.<\/p>\n<p>4. Vacances de loisirs et excursions de week-end<br \/>\nPendant les week-ends ou les courts s\u00e9jours, les sacs de voyage de marque sont un bon compagnon de voyage en raison de leur l\u00e9g\u00e8ret\u00e9, de leur portabilit\u00e9 et de leur grande capacit\u00e9. Qu'il s'agisse de vacances au bord de la mer ou de visites en ville, ce type de sac peut facilement contenir des v\u00eatements de rechange, des appareils photo, des livres et d'autres \u00e9quipements de divertissement, ce qui rend le voyage plus d\u00e9tendu et plus agr\u00e9able.<\/p>\n<p>5. Polyvalence multi-sc\u00e9narios<br \/>\nLes sacs de sport de marque ne sont pas seulement adapt\u00e9s aux voyages, au fitness et aux voyages d'affaires, mais leur polyvalence et leur sens de la mode en font \u00e9galement un choix id\u00e9al pour les d\u00e9placements quotidiens, la vie sur le campus et m\u00eame les activit\u00e9s de plein air. Qu'il soit associ\u00e9 \u00e0 des v\u00eatements de sport, \u00e0 des v\u00eatements d\u00e9contract\u00e9s ou \u00e0 des tenues de soir\u00e9e, ce sac peut afficher un style unique gr\u00e2ce \u00e0 diff\u00e9rentes combinaisons de style, afin de r\u00e9pondre aux besoins d'utilisation en diverses occasions.<\/p>\n<p>Sc\u00e9narios d'application<br \/>\n1. Voyages d'affaires<br \/>\nDans un environnement professionnel en constante \u00e9volution, le temps et l'efficacit\u00e9 sont particuli\u00e8rement importants. Gr\u00e2ce \u00e0 leur grande capacit\u00e9 et \u00e0 leur conception multi-compartiments, les sacs de sport de marque peuvent raisonnablement contenir des documents, des ordinateurs, des v\u00eatements et des fournitures de bureau essentielles dans le m\u00eame sac, ce qui permet aux hommes et femmes d'affaires de faire face facilement \u00e0 diverses situations d'urgence. En m\u00eame temps, son apparence \u00e9l\u00e9gante et sa texture haut de gamme peuvent \u00e9galement montrer une image professionnelle dans les occasions d'affaires, ajoutant des points \u00e0 l'image globale.<\/p>\n<p>2. Voyages de longue dur\u00e9e et voyages de courte dur\u00e9e<br \/>\nQu'il s'agisse d'un voyage de longue dur\u00e9e ou d'un court week-end, la valise doit souvent tenir compte de la grande capacit\u00e9 et de la portabilit\u00e9. Designer Duffle Bags a trouv\u00e9 un \u00e9quilibre entre les deux. Gr\u00e2ce \u00e0 une conception interne raisonnable et \u00e0 des mat\u00e9riaux l\u00e9gers, le sac peut contenir un grand nombre d'articles tout en restant facile \u00e0 transporter. Pendant le voyage, les compartiments aux fonctions diff\u00e9rentes peuvent aider les voyageurs \u00e0 trouver rapidement les articles dont ils ont besoin, \u00e0 r\u00e9duire le temps de tri des bagages et \u00e0 am\u00e9liorer l'efficacit\u00e9 du voyage.<\/p>\n<p>3. Gymnastique et activit\u00e9s sportives<br \/>\nLes adeptes du fitness ont besoin de sacs non seulement en termes de capacit\u00e9, mais aussi en termes de commodit\u00e9 et de durabilit\u00e9. Les sacs de sport de marque sont g\u00e9n\u00e9ralement fabriqu\u00e9s dans des mat\u00e9riaux imperm\u00e9ables et antisalissures, avec une conception respirante et des compartiments sp\u00e9ciaux pour les chaussures, de sorte que l'\u00e9quipement sportif et les articles quotidiens peuvent \u00eatre efficacement s\u00e9par\u00e9s pour \u00e9viter que les odeurs et l'humidit\u00e9 n'interf\u00e8rent les uns avec les autres. Qu'il s'agisse de se changer apr\u00e8s une course matinale ou d'un court s\u00e9jour \u00e0 la salle de sport, ce type de sac est tr\u00e8s pratique pour les athl\u00e8tes.<\/p>\n<p>4. Achats occasionnels et d\u00e9placements quotidiens<br \/>\nOutre les voyages et le fitness, les sacs de sport de marque sont \u00e9galement largement utilis\u00e9s dans la vie quotidienne. Certains sacs \u00e0 la mode peuvent \u00eatre utilis\u00e9s comme sacs de transport quotidien ou comme sacs \u00e0 provisions, ce qui permet non seulement de r\u00e9pondre aux besoins de stockage des articles quotidiens, mais aussi d'\u00eatre utilis\u00e9 comme article de style pour \u00e9gayer l'ensemble de la tenue. Associ\u00e9s \u00e0 diff\u00e9rents v\u00eatements, ils peuvent non seulement afficher un style d\u00e9contract\u00e9, mais aussi refl\u00e9ter la recherche d'une vie de qualit\u00e9.<\/p>\n<p>5. Activit\u00e9s de plein air et camping<br \/>\nPour les amateurs d'activit\u00e9s de plein air, les sacs de voyage design durables, imperm\u00e9ables \u00e0 l'eau et \u00e0 la poussi\u00e8re sont sans aucun doute des \u00e9quipements indispensables. Qu'il s'agisse de camping, de pique-nique ou de courtes randonn\u00e9es, ces sacs peuvent jouer un r\u00f4le dans des environnements ext\u00e9rieurs complexes. La coque robuste et la conception anti-collision permettent non seulement de prot\u00e9ger efficacement le contenu, mais aussi de r\u00e9sister au vent et \u00e0 la pluie, garantissant ainsi une utilisation \u00e0 long terme lors des activit\u00e9s de plein air.<\/p>\n<p>Comment entretenir les sacs de sport de marque<br \/>\nAfin de prolonger la dur\u00e9e de vie des sacs de sport de marque et de conserver leur belle apparence et leurs bonnes fonctions, l'entretien quotidien est tr\u00e8s important. Voici quelques m\u00e9thodes et pr\u00e9cautions d'entretien courantes :<\/p>\n<p>1. Nettoyage quotidien<br \/>\nNettoyage de la surface : Il est recommand\u00e9 d'essuyer r\u00e9guli\u00e8rement la surface du sac \u00e0 l'aide d'un chiffon doux et humide ou d'une serviette de nettoyage sp\u00e9ciale, en particulier la surface en cuir ou en mat\u00e9riaux sp\u00e9ciaux, afin d'\u00e9viter la poussi\u00e8re et les taches. Si vous rencontrez des taches tenaces, vous pouvez utiliser un d\u00e9tergent neutre avec mod\u00e9ration, mais veillez \u00e0 ne pas trop forcer pour ne pas endommager la surface du mat\u00e9riau.<br \/>\nNettoyage de la doublure : Il est recommand\u00e9 d'utiliser une m\u00e9thode de nettoyage douce pour la doublure, par exemple en la frottant doucement avec de l'eau chaude, puis en absorbant l'humidit\u00e9 avec une serviette propre pour garder la doublure s\u00e8che afin d'\u00e9viter les moisissures ou les odeurs.<br \/>\n2. Traitement imperm\u00e9able \u00e0 l'eau<br \/>\nPour les sacs en cuir naturel ou en toile, il est recommand\u00e9 d'appliquer un spray imperm\u00e9abilisant avant la premi\u00e8re utilisation ou apr\u00e8s le nettoyage afin d'am\u00e9liorer la r\u00e9sistance \u00e0 l'eau de la surface du sac et d'emp\u00eacher la pluie ou la sueur de p\u00e9n\u00e9trer. Par ailleurs, en cas d'utilisation par temps de pluie ou dans un environnement humide, il convient de veiller \u00e0 l'\u00e9tanch\u00e9it\u00e9 du sac et d'\u00e9viter toute exposition prolong\u00e9e \u00e0 un environnement humide.<br \/>\n3. Stockage et conservation<br \/>\nVentilation s\u00e8che : Lorsqu'il n'est pas utilis\u00e9, le sac doit \u00eatre rang\u00e9 dans un endroit sec et ventil\u00e9, sans exposition directe au soleil. Une exposition prolong\u00e9e \u00e0 la lumi\u00e8re du soleil peut facilement entra\u00eener une d\u00e9coloration des couleurs ou un vieillissement des mat\u00e9riaux.<br \/>\nConservez la forme originale : Pendant le stockage, il est recommand\u00e9 de sortir les articles du sac et de conserver la forme originale du sac. Si n\u00e9cessaire, vous pouvez le remplir de journaux ou de coussins gonflables pour \u00e9viter qu'il ne se d\u00e9forme ou ne se froisse.<br \/>\n4. Inspection et entretien r\u00e9guliers<br \/>\nV\u00e9rifiez r\u00e9guli\u00e8rement si les coutures, la fermeture \u00e9clair, les fermetures et les sangles du sac sont l\u00e2ches ou endommag\u00e9es. Si des probl\u00e8mes sont constat\u00e9s, ils doivent \u00eatre r\u00e9par\u00e9s \u00e0 temps. Pour certains sacs haut de gamme, il est recommand\u00e9 de les confier \u00e0 des ateliers d'entretien professionnels pour qu'ils b\u00e9n\u00e9ficient d'un soin et d'une maintenance approfondis.<br \/>\nPour les sacs en cuir, outre l'imperm\u00e9abilisation, une huile ou une lotion d'entretien du cuir doit \u00eatre utilis\u00e9e pour l'entretien r\u00e9gulier afin de maintenir la surface du cuir souple et brillante et d'\u00e9viter les craquelures.<br \/>\n5. Pr\u00e9cautions d'emploi<br \/>\nEssayez d'\u00e9viter toute surcharge. Une surcharge peut facilement entra\u00eener une d\u00e9formation du sac ou un arrachement des coutures, ce qui nuit \u00e0 l'aspect g\u00e9n\u00e9ral et \u00e0 la durabilit\u00e9 du sac.<br \/>\nSi le sac est tach\u00e9 d'huile ou de taches sp\u00e9ciales dues \u00e0 une utilisation en ext\u00e9rieur, il est recommand\u00e9 de le nettoyer d\u00e8s que possible afin d'\u00e9viter que les taches ne restent longtemps et ne soient difficiles \u00e0 enlever.<\/p>","protected":false},"excerpt":{"rendered":"<table style=\"border-collapse: collapse; width: 414.02pt;\" border=\"0\" width=\"690\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 56.00pt;\">\n<td class=\"et2\" style=\"height: 56.00pt; width: 48.00pt;\" width=\"80\" height=\"93\">LOGO<\/td>\n<td class=\"et3\" style=\"width: 366.00pt;\" width=\"610\">Accepter le service OEM &amp; ODM \/ Personnalis\u00e9<\/td>\n<\/tr>\n<tr style=\"height: 56.00pt;\">\n<td class=\"et2\" style=\"height: 56.00pt; width: 48.00pt;\" width=\"80\" height=\"93\">Type d'usine<\/td>\n<td class=\"et3\" style=\"width: 366.00pt;\" width=\"610\">Production\/fabrication\/OEM\/transport \u00e0 guichet unique pour les clients<\/td>\n<\/tr>\n<tr style=\"height: 56.00pt;\">\n<td class=\"et2\" style=\"height: 56.00pt; width: 48.00pt;\" width=\"80\" height=\"93\">MOQ<\/td>\n<td class=\"et3\" style=\"width: 366.00pt;\" width=\"610\">50pcs en cuir v\u00e9ritable \/ 100pcs avec 2 couleurs dans d'autres mat\u00e9riaux.<\/td>\n<\/tr>\n<tr style=\"height: 56.00pt;\">\n<td class=\"et2\" style=\"height: 56.00pt; width: 48.00pt;\" width=\"80\" height=\"93\">Couleur<\/td>\n<td class=\"et3\" style=\"width: 366.00pt;\" width=\"610\">Noir, rouge, bleu, marron ou couleurs personnalis\u00e9es accept\u00e9es.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"featured_media":1273,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":["post-1272","product","type-product","status-publish","has-post-thumbnail","product_cat-travel-duffel-bag","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/bsbagfactory.com\/fr_ca\/wp-json\/wp\/v2\/product\/1272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bsbagfactory.com\/fr_ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bsbagfactory.com\/fr_ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bsbagfactory.com\/fr_ca\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/bsbagfactory.com\/fr_ca\/wp-json\/wp\/v2\/media?parent=1272"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bsbagfactory.com\/fr_ca\/wp-json\/wp\/v2\/product_brand?post=1272"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bsbagfactory.com\/fr_ca\/wp-json\/wp\/v2\/product_cat?post=1272"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bsbagfactory.com\/fr_ca\/wp-json\/wp\/v2\/product_tag?post=1272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}